{"id":10156,"date":"2012-04-04T14:10:30","date_gmt":"2012-04-04T12:10:30","guid":{"rendered":"http:\/\/www.prosos.org\/sosvz\/?guid=9ffa804eb8e65ca976da55ec84ee4540"},"modified":"2012-04-04T14:10:30","modified_gmt":"2012-04-04T12:10:30","slug":"einbruchserie-aufgeklart","status":"publish","type":"post","link":"https:\/\/www.prosos.org\/sosvz\/einbruchserie-aufgeklart-10156.html","title":{"rendered":"Einbruchserie aufgekl\u00e4rt"},"content":{"rendered":"MARQUARTSTEIN, Lkr. Traunstein. Zwei junge Serieneinbrecher konnten am 1. April auf frischer Tat festgenommen werden. Gegen den 19-j\u00e4hrigen Hauptt\u00e4ter wurde die Untersuchungshaft angeordnet.  \n<p class=\"syndicated-attribution\"><br \/><a target='_blank' href='http:\/\/www.polizei.bayern.de\/oberbayern\/news\/presse\/aktuell\/index.html\/154383'> komplette Meldung auf Polizei Bayern lesen<\/a><br \/><\/p>","protected":false},"excerpt":{"rendered":"<p>MARQUARTSTEIN, Lkr. Traunstein. Zwei junge Serieneinbrecher konnten am 1. April auf frischer Tat festgenommen werden. Gegen den 19-j\u00e4hrigen Hauptt\u00e4ter wurde die Untersuchungshaft angeordnet.  <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-10156","post","type-post","status-publish","format-standard","hentry","category-nayern"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Einbruchserie aufgekl\u00e4rt<\/title>\n<meta name=\"description\" content=\"MARQUARTSTEIN, Lkr. Traunstein. Zwei junge Serieneinbrecher konnten am 1. April auf frischer Tat festgenommen werden. Gegen den 19-j\u00e4hrigen Hauptt\u00e4ter wurde die Untersuchungshaft angeordnet.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.prosos.org\/sosvz\/einbruchserie-aufgeklart-10156.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Einbruchserie aufgekl\u00e4rt\" \/>\n<meta property=\"og:description\" content=\"MARQUARTSTEIN, Lkr. Traunstein. Zwei junge Serieneinbrecher konnten am 1. April auf frischer Tat festgenommen werden. Gegen den 19-j\u00e4hrigen Hauptt\u00e4ter wurde die Untersuchungshaft angeordnet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.prosos.org\/sosvz\/einbruchserie-aufgeklart-10156.html\" \/>\n<meta property=\"og:site_name\" content=\"ProSOS - sosVZ\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-04T12:10:30+00:00\" \/>\n<meta name=\"author\" content=\"Polizei Bayern\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Polizei Bayern\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/einbruchserie-aufgeklart-10156.html\",\"url\":\"https:\/\/www.prosos.org\/sosvz\/einbruchserie-aufgeklart-10156.html\",\"name\":\"Einbruchserie aufgekl\u00e4rt\",\"isPartOf\":{\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#website\"},\"datePublished\":\"2012-04-04T12:10:30+00:00\",\"author\":{\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/fbd66aeac098e28acf1869332c6e55e9\"},\"description\":\"MARQUARTSTEIN, Lkr. Traunstein. Zwei junge Serieneinbrecher konnten am 1. April auf frischer Tat festgenommen werden. Gegen den 19-j\u00e4hrigen Hauptt\u00e4ter wurde die Untersuchungshaft angeordnet.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.prosos.org\/sosvz\/einbruchserie-aufgeklart-10156.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.prosos.org\/sosvz\/einbruchserie-aufgeklart-10156.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/einbruchserie-aufgeklart-10156.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.prosos.org\/sosvz\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einbruchserie aufgekl\u00e4rt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#website\",\"url\":\"https:\/\/www.prosos.org\/sosvz\/\",\"name\":\"ProSOS - sosVZ\",\"description\":\"Die Coummunity f\u00fcr Polizei, Feuerwehr, Rettungsdienste und Selbstschutz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.prosos.org\/sosvz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/fbd66aeac098e28acf1869332c6e55e9\",\"name\":\"Polizei Bayern\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a483f747047c1dc1556555639a19986e42d28bda61988c35164221a541236fce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a483f747047c1dc1556555639a19986e42d28bda61988c35164221a541236fce?s=96&d=mm&r=g\",\"caption\":\"Polizei Bayern\"},\"sameAs\":[\"http:\/\/www.polizei.bayern.de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Einbruchserie aufgekl\u00e4rt","description":"MARQUARTSTEIN, Lkr. Traunstein. Zwei junge Serieneinbrecher konnten am 1. April auf frischer Tat festgenommen werden. Gegen den 19-j\u00e4hrigen Hauptt\u00e4ter wurde die Untersuchungshaft angeordnet.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.prosos.org\/sosvz\/einbruchserie-aufgeklart-10156.html","og_locale":"de_DE","og_type":"article","og_title":"Einbruchserie aufgekl\u00e4rt","og_description":"MARQUARTSTEIN, Lkr. Traunstein. Zwei junge Serieneinbrecher konnten am 1. April auf frischer Tat festgenommen werden. Gegen den 19-j\u00e4hrigen Hauptt\u00e4ter wurde die Untersuchungshaft angeordnet.","og_url":"https:\/\/www.prosos.org\/sosvz\/einbruchserie-aufgeklart-10156.html","og_site_name":"ProSOS - sosVZ","article_published_time":"2012-04-04T12:10:30+00:00","author":"Polizei Bayern","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Polizei Bayern"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.prosos.org\/sosvz\/einbruchserie-aufgeklart-10156.html","url":"https:\/\/www.prosos.org\/sosvz\/einbruchserie-aufgeklart-10156.html","name":"Einbruchserie aufgekl\u00e4rt","isPartOf":{"@id":"https:\/\/www.prosos.org\/sosvz\/#website"},"datePublished":"2012-04-04T12:10:30+00:00","author":{"@id":"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/fbd66aeac098e28acf1869332c6e55e9"},"description":"MARQUARTSTEIN, Lkr. Traunstein. Zwei junge Serieneinbrecher konnten am 1. April auf frischer Tat festgenommen werden. Gegen den 19-j\u00e4hrigen Hauptt\u00e4ter wurde die Untersuchungshaft angeordnet.","breadcrumb":{"@id":"https:\/\/www.prosos.org\/sosvz\/einbruchserie-aufgeklart-10156.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.prosos.org\/sosvz\/einbruchserie-aufgeklart-10156.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.prosos.org\/sosvz\/einbruchserie-aufgeklart-10156.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.prosos.org\/sosvz"},{"@type":"ListItem","position":2,"name":"Einbruchserie aufgekl\u00e4rt"}]},{"@type":"WebSite","@id":"https:\/\/www.prosos.org\/sosvz\/#website","url":"https:\/\/www.prosos.org\/sosvz\/","name":"ProSOS - sosVZ","description":"Die Coummunity f\u00fcr Polizei, Feuerwehr, Rettungsdienste und Selbstschutz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.prosos.org\/sosvz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/fbd66aeac098e28acf1869332c6e55e9","name":"Polizei Bayern","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a483f747047c1dc1556555639a19986e42d28bda61988c35164221a541236fce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a483f747047c1dc1556555639a19986e42d28bda61988c35164221a541236fce?s=96&d=mm&r=g","caption":"Polizei Bayern"},"sameAs":["http:\/\/www.polizei.bayern.de"]}]}},"_links":{"self":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/posts\/10156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/comments?post=10156"}],"version-history":[{"count":0,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/posts\/10156\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/media?parent=10156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/categories?post=10156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/tags?post=10156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}