{"id":10157,"date":"2012-04-04T14:10:30","date_gmt":"2012-04-04T12:10:30","guid":{"rendered":"http:\/\/www.prosos.org\/sosvz\/?guid=f313747c89a73f32ac67873d749992cf"},"modified":"2012-04-04T14:10:30","modified_gmt":"2012-04-04T12:10:30","slug":"polizeiliches-resumee-zum-gestrigen-champions-league-spiel","status":"publish","type":"post","link":"https:\/\/www.prosos.org\/sosvz\/polizeiliches-resumee-zum-gestrigen-champions-league-spiel-10157.html","title":{"rendered":"Polizeiliches Res\u00fcmee zum gestrigen Champions-League-Spiel"},"content":{"rendered":"M\u00dcNCHEN. Am Dienstag, 03.04.2012, um 20.45 Uhr, fand in M\u00fcnchen das Champions-League-Spiel (Viertelfinale\/R\u00fcckspiel) zwischen dem FC Bayern M\u00fcnchen und Olympique Marseille vor 66.000 Zuschauern (davon etwa 2.000 Gastfans) statt. \n\n<p class=\"syndicated-attribution\"><br \/><a target='_blank' href='http:\/\/www.polizei.bayern.de\/muenchen\/news\/presse\/aktuell\/index.html\/154379'> komplette Meldung auf Polizei Bayern lesen<\/a><br \/><\/p>","protected":false},"excerpt":{"rendered":"<p>M\u00dcNCHEN. Am Dienstag, 03.04.2012, um 20.45 Uhr, fand in M\u00fcnchen das Champions-League-Spiel (Viertelfinale\/R\u00fcckspiel) zwischen dem FC Bayern M\u00fcnchen und Olympique Marseille vor 66.000 Zuschauern (davon etwa 2.000 Gastfans) statt. <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-10157","post","type-post","status-publish","format-standard","hentry","category-nayern"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Polizeiliches Res\u00fcmee zum gestrigen Champions-League-Spiel<\/title>\n<meta name=\"description\" content=\"M\u00dcNCHEN. Am Dienstag, 03.04.2012, um 20.45 Uhr, fand in M\u00fcnchen das Champions-League-Spiel (Viertelfinale\/R\u00fcckspiel) zwischen dem FC Bayern M\u00fcnchen und Olympique Marseille vor 66.000 Zuschauern (davon etwa 2.000 Gastfans) statt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.prosos.org\/sosvz\/polizeiliches-resumee-zum-gestrigen-champions-league-spiel-10157.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Polizeiliches Res\u00fcmee zum gestrigen Champions-League-Spiel\" \/>\n<meta property=\"og:description\" content=\"M\u00dcNCHEN. Am Dienstag, 03.04.2012, um 20.45 Uhr, fand in M\u00fcnchen das Champions-League-Spiel (Viertelfinale\/R\u00fcckspiel) zwischen dem FC Bayern M\u00fcnchen und Olympique Marseille vor 66.000 Zuschauern (davon etwa 2.000 Gastfans) statt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.prosos.org\/sosvz\/polizeiliches-resumee-zum-gestrigen-champions-league-spiel-10157.html\" \/>\n<meta property=\"og:site_name\" content=\"ProSOS - sosVZ\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-04T12:10:30+00:00\" \/>\n<meta name=\"author\" content=\"Polizei Bayern\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Polizei Bayern\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/polizeiliches-resumee-zum-gestrigen-champions-league-spiel-10157.html\",\"url\":\"https:\/\/www.prosos.org\/sosvz\/polizeiliches-resumee-zum-gestrigen-champions-league-spiel-10157.html\",\"name\":\"Polizeiliches Res\u00fcmee zum gestrigen Champions-League-Spiel\",\"isPartOf\":{\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#website\"},\"datePublished\":\"2012-04-04T12:10:30+00:00\",\"author\":{\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/fbd66aeac098e28acf1869332c6e55e9\"},\"description\":\"M\u00dcNCHEN. Am Dienstag, 03.04.2012, um 20.45 Uhr, fand in M\u00fcnchen das Champions-League-Spiel (Viertelfinale\/R\u00fcckspiel) zwischen dem FC Bayern M\u00fcnchen und Olympique Marseille vor 66.000 Zuschauern (davon etwa 2.000 Gastfans) statt.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.prosos.org\/sosvz\/polizeiliches-resumee-zum-gestrigen-champions-league-spiel-10157.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.prosos.org\/sosvz\/polizeiliches-resumee-zum-gestrigen-champions-league-spiel-10157.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/polizeiliches-resumee-zum-gestrigen-champions-league-spiel-10157.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.prosos.org\/sosvz\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Polizeiliches Res\u00fcmee zum gestrigen Champions-League-Spiel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#website\",\"url\":\"https:\/\/www.prosos.org\/sosvz\/\",\"name\":\"ProSOS - sosVZ\",\"description\":\"Die Coummunity f\u00fcr Polizei, Feuerwehr, Rettungsdienste und Selbstschutz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.prosos.org\/sosvz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/fbd66aeac098e28acf1869332c6e55e9\",\"name\":\"Polizei Bayern\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a483f747047c1dc1556555639a19986e42d28bda61988c35164221a541236fce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a483f747047c1dc1556555639a19986e42d28bda61988c35164221a541236fce?s=96&d=mm&r=g\",\"caption\":\"Polizei Bayern\"},\"sameAs\":[\"http:\/\/www.polizei.bayern.de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Polizeiliches Res\u00fcmee zum gestrigen Champions-League-Spiel","description":"M\u00dcNCHEN. Am Dienstag, 03.04.2012, um 20.45 Uhr, fand in M\u00fcnchen das Champions-League-Spiel (Viertelfinale\/R\u00fcckspiel) zwischen dem FC Bayern M\u00fcnchen und Olympique Marseille vor 66.000 Zuschauern (davon etwa 2.000 Gastfans) statt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.prosos.org\/sosvz\/polizeiliches-resumee-zum-gestrigen-champions-league-spiel-10157.html","og_locale":"de_DE","og_type":"article","og_title":"Polizeiliches Res\u00fcmee zum gestrigen Champions-League-Spiel","og_description":"M\u00dcNCHEN. Am Dienstag, 03.04.2012, um 20.45 Uhr, fand in M\u00fcnchen das Champions-League-Spiel (Viertelfinale\/R\u00fcckspiel) zwischen dem FC Bayern M\u00fcnchen und Olympique Marseille vor 66.000 Zuschauern (davon etwa 2.000 Gastfans) statt.","og_url":"https:\/\/www.prosos.org\/sosvz\/polizeiliches-resumee-zum-gestrigen-champions-league-spiel-10157.html","og_site_name":"ProSOS - sosVZ","article_published_time":"2012-04-04T12:10:30+00:00","author":"Polizei Bayern","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Polizei Bayern"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.prosos.org\/sosvz\/polizeiliches-resumee-zum-gestrigen-champions-league-spiel-10157.html","url":"https:\/\/www.prosos.org\/sosvz\/polizeiliches-resumee-zum-gestrigen-champions-league-spiel-10157.html","name":"Polizeiliches Res\u00fcmee zum gestrigen Champions-League-Spiel","isPartOf":{"@id":"https:\/\/www.prosos.org\/sosvz\/#website"},"datePublished":"2012-04-04T12:10:30+00:00","author":{"@id":"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/fbd66aeac098e28acf1869332c6e55e9"},"description":"M\u00dcNCHEN. Am Dienstag, 03.04.2012, um 20.45 Uhr, fand in M\u00fcnchen das Champions-League-Spiel (Viertelfinale\/R\u00fcckspiel) zwischen dem FC Bayern M\u00fcnchen und Olympique Marseille vor 66.000 Zuschauern (davon etwa 2.000 Gastfans) statt.","breadcrumb":{"@id":"https:\/\/www.prosos.org\/sosvz\/polizeiliches-resumee-zum-gestrigen-champions-league-spiel-10157.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.prosos.org\/sosvz\/polizeiliches-resumee-zum-gestrigen-champions-league-spiel-10157.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.prosos.org\/sosvz\/polizeiliches-resumee-zum-gestrigen-champions-league-spiel-10157.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.prosos.org\/sosvz"},{"@type":"ListItem","position":2,"name":"Polizeiliches Res\u00fcmee zum gestrigen Champions-League-Spiel"}]},{"@type":"WebSite","@id":"https:\/\/www.prosos.org\/sosvz\/#website","url":"https:\/\/www.prosos.org\/sosvz\/","name":"ProSOS - sosVZ","description":"Die Coummunity f\u00fcr Polizei, Feuerwehr, Rettungsdienste und Selbstschutz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.prosos.org\/sosvz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/fbd66aeac098e28acf1869332c6e55e9","name":"Polizei Bayern","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a483f747047c1dc1556555639a19986e42d28bda61988c35164221a541236fce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a483f747047c1dc1556555639a19986e42d28bda61988c35164221a541236fce?s=96&d=mm&r=g","caption":"Polizei Bayern"},"sameAs":["http:\/\/www.polizei.bayern.de"]}]}},"_links":{"self":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/posts\/10157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/comments?post=10157"}],"version-history":[{"count":0,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/posts\/10157\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/media?parent=10157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/categories?post=10157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/tags?post=10157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}