{"id":52993,"date":"2019-11-23T14:21:31","date_gmt":"2019-11-23T13:21:31","guid":{"rendered":"http:\/\/www.prosos.org\/sosvz\/?guid=795d66ea0d3c7c0f7f1ce75718a12f4d"},"modified":"2019-11-23T14:21:31","modified_gmt":"2019-11-23T13:21:31","slug":"traktorsternfahrt-nach-berlin-fahrtstrecke-nach-thueringen-ueber-bab-71","status":"publish","type":"post","link":"https:\/\/www.prosos.org\/sosvz\/traktorsternfahrt-nach-berlin-fahrtstrecke-nach-thueringen-ueber-bab-71-52993.html","title":{"rendered":"\u201eTraktorsternfahrt nach Berlin\u201c \u2013 Fahrtstrecke nach Th\u00fcringen \u00fcber BAB 71"},"content":{"rendered":"UNTERFRANKEN. Die Fahrtstrecke der beim Landratsamt Schweinfurt f\u00fcr Sonntag angezeigten Traktorsternfahrt verl\u00e4uft \u00fcber die BAB 71 bis zur Landesgrenze nach Th\u00fcringen. Die Beeintr\u00e4chtigungen f\u00fcr Anwohner der Gemeinden entlang der Strecke werden sich dementsprechend in Grenzen halten. Auf der Autobahn flie\u00dft der Verkehr einspurig.\n<p class=\"syndicated-attribution\"><br \/><a target='_blank' href='http:\/\/www.polizei.bayern.de\/unterfranken\/news\/presse\/aktuell\/index.html\/306153'> komplette Meldung auf Polizei Bayern lesen<\/a><br \/><\/p>","protected":false},"excerpt":{"rendered":"<p>UNTERFRANKEN. Die Fahrtstrecke der beim Landratsamt Schweinfurt f\u00fcr Sonntag angezeigten Traktorsternfahrt verl\u00e4uft \u00fcber die BAB 71 bis zur Landesgrenze nach Th\u00fcringen. Die Beeintr\u00e4chtigungen f\u00fcr Anwohner der Gemeinden entlang der Strecke werden sich de&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-52993","post","type-post","status-publish","format-standard","hentry","category-nayern"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u201eTraktorsternfahrt nach Berlin\u201c \u2013 Fahrtstrecke nach Th\u00fcringen \u00fcber BAB 71<\/title>\n<meta name=\"description\" content=\"UNTERFRANKEN. Die Fahrtstrecke der beim Landratsamt Schweinfurt f\u00fcr Sonntag angezeigten Traktorsternfahrt verl\u00e4uft \u00fcber die BAB 71 bis zur Landesgrenze nach Th\u00fcringen. Die Beeintr\u00e4chtigungen f\u00fcr Anwohner der Gemeinden entlang der Strecke werden sich de...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.prosos.org\/sosvz\/traktorsternfahrt-nach-berlin-fahrtstrecke-nach-thueringen-ueber-bab-71-52993.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201eTraktorsternfahrt nach Berlin\u201c \u2013 Fahrtstrecke nach Th\u00fcringen \u00fcber BAB 71\" \/>\n<meta property=\"og:description\" content=\"UNTERFRANKEN. Die Fahrtstrecke der beim Landratsamt Schweinfurt f\u00fcr Sonntag angezeigten Traktorsternfahrt verl\u00e4uft \u00fcber die BAB 71 bis zur Landesgrenze nach Th\u00fcringen. Die Beeintr\u00e4chtigungen f\u00fcr Anwohner der Gemeinden entlang der Strecke werden sich de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.prosos.org\/sosvz\/traktorsternfahrt-nach-berlin-fahrtstrecke-nach-thueringen-ueber-bab-71-52993.html\" \/>\n<meta property=\"og:site_name\" content=\"ProSOS - sosVZ\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-23T13:21:31+00:00\" \/>\n<meta name=\"author\" content=\"Polizei Bayern\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Polizei Bayern\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/traktorsternfahrt-nach-berlin-fahrtstrecke-nach-thueringen-ueber-bab-71-52993.html\",\"url\":\"https:\/\/www.prosos.org\/sosvz\/traktorsternfahrt-nach-berlin-fahrtstrecke-nach-thueringen-ueber-bab-71-52993.html\",\"name\":\"\u201eTraktorsternfahrt nach Berlin\u201c \u2013 Fahrtstrecke nach Th\u00fcringen \u00fcber BAB 71\",\"isPartOf\":{\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#website\"},\"datePublished\":\"2019-11-23T13:21:31+00:00\",\"author\":{\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/fbd66aeac098e28acf1869332c6e55e9\"},\"description\":\"UNTERFRANKEN. Die Fahrtstrecke der beim Landratsamt Schweinfurt f\u00fcr Sonntag angezeigten Traktorsternfahrt verl\u00e4uft \u00fcber die BAB 71 bis zur Landesgrenze nach Th\u00fcringen. Die Beeintr\u00e4chtigungen f\u00fcr Anwohner der Gemeinden entlang der Strecke werden sich de...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.prosos.org\/sosvz\/traktorsternfahrt-nach-berlin-fahrtstrecke-nach-thueringen-ueber-bab-71-52993.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.prosos.org\/sosvz\/traktorsternfahrt-nach-berlin-fahrtstrecke-nach-thueringen-ueber-bab-71-52993.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/traktorsternfahrt-nach-berlin-fahrtstrecke-nach-thueringen-ueber-bab-71-52993.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.prosos.org\/sosvz\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201eTraktorsternfahrt nach Berlin\u201c \u2013 Fahrtstrecke nach Th\u00fcringen \u00fcber BAB 71\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#website\",\"url\":\"https:\/\/www.prosos.org\/sosvz\/\",\"name\":\"ProSOS - sosVZ\",\"description\":\"Die Coummunity f\u00fcr Polizei, Feuerwehr, Rettungsdienste und Selbstschutz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.prosos.org\/sosvz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/fbd66aeac098e28acf1869332c6e55e9\",\"name\":\"Polizei Bayern\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a483f747047c1dc1556555639a19986e42d28bda61988c35164221a541236fce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a483f747047c1dc1556555639a19986e42d28bda61988c35164221a541236fce?s=96&d=mm&r=g\",\"caption\":\"Polizei Bayern\"},\"sameAs\":[\"http:\/\/www.polizei.bayern.de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201eTraktorsternfahrt nach Berlin\u201c \u2013 Fahrtstrecke nach Th\u00fcringen \u00fcber BAB 71","description":"UNTERFRANKEN. Die Fahrtstrecke der beim Landratsamt Schweinfurt f\u00fcr Sonntag angezeigten Traktorsternfahrt verl\u00e4uft \u00fcber die BAB 71 bis zur Landesgrenze nach Th\u00fcringen. Die Beeintr\u00e4chtigungen f\u00fcr Anwohner der Gemeinden entlang der Strecke werden sich de...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.prosos.org\/sosvz\/traktorsternfahrt-nach-berlin-fahrtstrecke-nach-thueringen-ueber-bab-71-52993.html","og_locale":"de_DE","og_type":"article","og_title":"\u201eTraktorsternfahrt nach Berlin\u201c \u2013 Fahrtstrecke nach Th\u00fcringen \u00fcber BAB 71","og_description":"UNTERFRANKEN. Die Fahrtstrecke der beim Landratsamt Schweinfurt f\u00fcr Sonntag angezeigten Traktorsternfahrt verl\u00e4uft \u00fcber die BAB 71 bis zur Landesgrenze nach Th\u00fcringen. Die Beeintr\u00e4chtigungen f\u00fcr Anwohner der Gemeinden entlang der Strecke werden sich de...","og_url":"https:\/\/www.prosos.org\/sosvz\/traktorsternfahrt-nach-berlin-fahrtstrecke-nach-thueringen-ueber-bab-71-52993.html","og_site_name":"ProSOS - sosVZ","article_published_time":"2019-11-23T13:21:31+00:00","author":"Polizei Bayern","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Polizei Bayern"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.prosos.org\/sosvz\/traktorsternfahrt-nach-berlin-fahrtstrecke-nach-thueringen-ueber-bab-71-52993.html","url":"https:\/\/www.prosos.org\/sosvz\/traktorsternfahrt-nach-berlin-fahrtstrecke-nach-thueringen-ueber-bab-71-52993.html","name":"\u201eTraktorsternfahrt nach Berlin\u201c \u2013 Fahrtstrecke nach Th\u00fcringen \u00fcber BAB 71","isPartOf":{"@id":"https:\/\/www.prosos.org\/sosvz\/#website"},"datePublished":"2019-11-23T13:21:31+00:00","author":{"@id":"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/fbd66aeac098e28acf1869332c6e55e9"},"description":"UNTERFRANKEN. Die Fahrtstrecke der beim Landratsamt Schweinfurt f\u00fcr Sonntag angezeigten Traktorsternfahrt verl\u00e4uft \u00fcber die BAB 71 bis zur Landesgrenze nach Th\u00fcringen. Die Beeintr\u00e4chtigungen f\u00fcr Anwohner der Gemeinden entlang der Strecke werden sich de...","breadcrumb":{"@id":"https:\/\/www.prosos.org\/sosvz\/traktorsternfahrt-nach-berlin-fahrtstrecke-nach-thueringen-ueber-bab-71-52993.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.prosos.org\/sosvz\/traktorsternfahrt-nach-berlin-fahrtstrecke-nach-thueringen-ueber-bab-71-52993.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.prosos.org\/sosvz\/traktorsternfahrt-nach-berlin-fahrtstrecke-nach-thueringen-ueber-bab-71-52993.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.prosos.org\/sosvz"},{"@type":"ListItem","position":2,"name":"\u201eTraktorsternfahrt nach Berlin\u201c \u2013 Fahrtstrecke nach Th\u00fcringen \u00fcber BAB 71"}]},{"@type":"WebSite","@id":"https:\/\/www.prosos.org\/sosvz\/#website","url":"https:\/\/www.prosos.org\/sosvz\/","name":"ProSOS - sosVZ","description":"Die Coummunity f\u00fcr Polizei, Feuerwehr, Rettungsdienste und Selbstschutz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.prosos.org\/sosvz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/fbd66aeac098e28acf1869332c6e55e9","name":"Polizei Bayern","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a483f747047c1dc1556555639a19986e42d28bda61988c35164221a541236fce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a483f747047c1dc1556555639a19986e42d28bda61988c35164221a541236fce?s=96&d=mm&r=g","caption":"Polizei Bayern"},"sameAs":["http:\/\/www.polizei.bayern.de"]}]}},"_links":{"self":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/posts\/52993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/comments?post=52993"}],"version-history":[{"count":1,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/posts\/52993\/revisions"}],"predecessor-version":[{"id":52994,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/posts\/52993\/revisions\/52994"}],"wp:attachment":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/media?parent=52993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/categories?post=52993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/tags?post=52993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}