{"id":52997,"date":"2019-11-23T14:21:32","date_gmt":"2019-11-23T13:21:32","guid":{"rendered":"http:\/\/www.prosos.org\/sosvz\/?guid=0d61cf2991727c8309da05f5b184e90e"},"modified":"2019-11-23T14:21:32","modified_gmt":"2019-11-23T13:21:32","slug":"traktor-sternfahrt-nach-berlin-verkehrsbehinderungen-erwartet","status":"publish","type":"post","link":"https:\/\/www.prosos.org\/sosvz\/traktor-sternfahrt-nach-berlin-verkehrsbehinderungen-erwartet-52997.html","title":{"rendered":"Traktor-Sternfahrt nach Berlin &#8211; Verkehrsbehinderungen erwartet"},"content":{"rendered":"INGOLSTADT. Am Dienstag, 26.11.2019, findet in Berlin eine Versammlung des B\u00fcndnisses \"Land schafft Verbindung\" statt, zu der aus ganz Deutschland Landwirte mit ihren Traktoren erwartet werden. Auch aus Oberbayern sind mehrere Hundert Traktoren angek\u00fcndigt, die sich am Montag Fr\u00fch (25.11.19) von einem zentralen Sammelpunkt im Landkreis Pfaffenhofen \/ Ilm aus auf den Weg nach Berlin machen werden.\n<p class=\"syndicated-attribution\"><br \/><a target='_blank' href='http:\/\/www.polizei.bayern.de\/oberbayern_nord\/news\/presse\/aktuell\/index.html\/306149'> komplette Meldung auf Polizei Bayern lesen<\/a><br \/><\/p>","protected":false},"excerpt":{"rendered":"<p>INGOLSTADT. Am Dienstag, 26.11.2019, findet in Berlin eine Versammlung des B\u00fcndnisses &#8222;Land schafft Verbindung&#8220; statt, zu der aus ganz Deutschland Landwirte mit ihren Traktoren erwartet werden. Auch aus Oberbayern sind mehrere Hundert Traktoren angek\u00fcn&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-52997","post","type-post","status-publish","format-standard","hentry","category-nayern"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Traktor-Sternfahrt nach Berlin - Verkehrsbehinderungen erwartet<\/title>\n<meta name=\"description\" content=\"INGOLSTADT. Am Dienstag, 26.11.2019, findet in Berlin eine Versammlung des B\u00fcndnisses &quot;Land schafft Verbindung&quot; statt, zu der aus ganz Deutschland Landwirte mit ihren Traktoren erwartet werden. Auch aus Oberbayern sind mehrere Hundert Traktoren angek\u00fcn...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.prosos.org\/sosvz\/traktor-sternfahrt-nach-berlin-verkehrsbehinderungen-erwartet-52997.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Traktor-Sternfahrt nach Berlin - Verkehrsbehinderungen erwartet\" \/>\n<meta property=\"og:description\" content=\"INGOLSTADT. Am Dienstag, 26.11.2019, findet in Berlin eine Versammlung des B\u00fcndnisses &quot;Land schafft Verbindung&quot; statt, zu der aus ganz Deutschland Landwirte mit ihren Traktoren erwartet werden. Auch aus Oberbayern sind mehrere Hundert Traktoren angek\u00fcn...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.prosos.org\/sosvz\/traktor-sternfahrt-nach-berlin-verkehrsbehinderungen-erwartet-52997.html\" \/>\n<meta property=\"og:site_name\" content=\"ProSOS - sosVZ\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-23T13:21:32+00:00\" \/>\n<meta name=\"author\" content=\"Polizei Bayern\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Polizei Bayern\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/traktor-sternfahrt-nach-berlin-verkehrsbehinderungen-erwartet-52997.html\",\"url\":\"https:\/\/www.prosos.org\/sosvz\/traktor-sternfahrt-nach-berlin-verkehrsbehinderungen-erwartet-52997.html\",\"name\":\"Traktor-Sternfahrt nach Berlin - Verkehrsbehinderungen erwartet\",\"isPartOf\":{\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#website\"},\"datePublished\":\"2019-11-23T13:21:32+00:00\",\"author\":{\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/fbd66aeac098e28acf1869332c6e55e9\"},\"description\":\"INGOLSTADT. Am Dienstag, 26.11.2019, findet in Berlin eine Versammlung des B\u00fcndnisses \\\"Land schafft Verbindung\\\" statt, zu der aus ganz Deutschland Landwirte mit ihren Traktoren erwartet werden. Auch aus Oberbayern sind mehrere Hundert Traktoren angek\u00fcn...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.prosos.org\/sosvz\/traktor-sternfahrt-nach-berlin-verkehrsbehinderungen-erwartet-52997.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.prosos.org\/sosvz\/traktor-sternfahrt-nach-berlin-verkehrsbehinderungen-erwartet-52997.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/traktor-sternfahrt-nach-berlin-verkehrsbehinderungen-erwartet-52997.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.prosos.org\/sosvz\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Traktor-Sternfahrt nach Berlin &#8211; Verkehrsbehinderungen erwartet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#website\",\"url\":\"https:\/\/www.prosos.org\/sosvz\/\",\"name\":\"ProSOS - sosVZ\",\"description\":\"Die Coummunity f\u00fcr Polizei, Feuerwehr, Rettungsdienste und Selbstschutz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.prosos.org\/sosvz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/fbd66aeac098e28acf1869332c6e55e9\",\"name\":\"Polizei Bayern\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a483f747047c1dc1556555639a19986e42d28bda61988c35164221a541236fce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a483f747047c1dc1556555639a19986e42d28bda61988c35164221a541236fce?s=96&d=mm&r=g\",\"caption\":\"Polizei Bayern\"},\"sameAs\":[\"http:\/\/www.polizei.bayern.de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Traktor-Sternfahrt nach Berlin - Verkehrsbehinderungen erwartet","description":"INGOLSTADT. Am Dienstag, 26.11.2019, findet in Berlin eine Versammlung des B\u00fcndnisses \"Land schafft Verbindung\" statt, zu der aus ganz Deutschland Landwirte mit ihren Traktoren erwartet werden. Auch aus Oberbayern sind mehrere Hundert Traktoren angek\u00fcn...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.prosos.org\/sosvz\/traktor-sternfahrt-nach-berlin-verkehrsbehinderungen-erwartet-52997.html","og_locale":"de_DE","og_type":"article","og_title":"Traktor-Sternfahrt nach Berlin - Verkehrsbehinderungen erwartet","og_description":"INGOLSTADT. Am Dienstag, 26.11.2019, findet in Berlin eine Versammlung des B\u00fcndnisses \"Land schafft Verbindung\" statt, zu der aus ganz Deutschland Landwirte mit ihren Traktoren erwartet werden. Auch aus Oberbayern sind mehrere Hundert Traktoren angek\u00fcn...","og_url":"https:\/\/www.prosos.org\/sosvz\/traktor-sternfahrt-nach-berlin-verkehrsbehinderungen-erwartet-52997.html","og_site_name":"ProSOS - sosVZ","article_published_time":"2019-11-23T13:21:32+00:00","author":"Polizei Bayern","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Polizei Bayern"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.prosos.org\/sosvz\/traktor-sternfahrt-nach-berlin-verkehrsbehinderungen-erwartet-52997.html","url":"https:\/\/www.prosos.org\/sosvz\/traktor-sternfahrt-nach-berlin-verkehrsbehinderungen-erwartet-52997.html","name":"Traktor-Sternfahrt nach Berlin - Verkehrsbehinderungen erwartet","isPartOf":{"@id":"https:\/\/www.prosos.org\/sosvz\/#website"},"datePublished":"2019-11-23T13:21:32+00:00","author":{"@id":"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/fbd66aeac098e28acf1869332c6e55e9"},"description":"INGOLSTADT. Am Dienstag, 26.11.2019, findet in Berlin eine Versammlung des B\u00fcndnisses \"Land schafft Verbindung\" statt, zu der aus ganz Deutschland Landwirte mit ihren Traktoren erwartet werden. Auch aus Oberbayern sind mehrere Hundert Traktoren angek\u00fcn...","breadcrumb":{"@id":"https:\/\/www.prosos.org\/sosvz\/traktor-sternfahrt-nach-berlin-verkehrsbehinderungen-erwartet-52997.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.prosos.org\/sosvz\/traktor-sternfahrt-nach-berlin-verkehrsbehinderungen-erwartet-52997.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.prosos.org\/sosvz\/traktor-sternfahrt-nach-berlin-verkehrsbehinderungen-erwartet-52997.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.prosos.org\/sosvz"},{"@type":"ListItem","position":2,"name":"Traktor-Sternfahrt nach Berlin &#8211; Verkehrsbehinderungen erwartet"}]},{"@type":"WebSite","@id":"https:\/\/www.prosos.org\/sosvz\/#website","url":"https:\/\/www.prosos.org\/sosvz\/","name":"ProSOS - sosVZ","description":"Die Coummunity f\u00fcr Polizei, Feuerwehr, Rettungsdienste und Selbstschutz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.prosos.org\/sosvz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/fbd66aeac098e28acf1869332c6e55e9","name":"Polizei Bayern","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a483f747047c1dc1556555639a19986e42d28bda61988c35164221a541236fce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a483f747047c1dc1556555639a19986e42d28bda61988c35164221a541236fce?s=96&d=mm&r=g","caption":"Polizei Bayern"},"sameAs":["http:\/\/www.polizei.bayern.de"]}]}},"_links":{"self":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/posts\/52997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/comments?post=52997"}],"version-history":[{"count":1,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/posts\/52997\/revisions"}],"predecessor-version":[{"id":52998,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/posts\/52997\/revisions\/52998"}],"wp:attachment":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/media?parent=52997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/categories?post=52997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/tags?post=52997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}