{"id":8368,"date":"2012-01-19T11:13:28","date_gmt":"2012-01-19T10:13:28","guid":{"rendered":"http:\/\/www.prosos.org\/sosvz\/?guid=9ec590019d989adeb758162bc43f3ad1"},"modified":"2012-01-19T11:13:28","modified_gmt":"2012-01-19T10:13:28","slug":"task-force-berat-starkungspakt-kommunen-politische-reprasentanten-ubernehmen-vermittlerrolle","status":"publish","type":"post","link":"https:\/\/www.prosos.org\/sosvz\/task-force-berat-starkungspakt-kommunen-politische-reprasentanten-ubernehmen-vermittlerrolle-8368.html","title":{"rendered":"Task Force ber\u00e4t St\u00e4rkungspakt-Kommunen \/ Politische Repr\u00e4sentanten \u00fcbernehmen Vermittlerrolle"},"content":{"rendered":"Eine Task Force wird ab sofort die 34-St\u00e4rkungspakt-Kommunen auf ihrem Weg zum Haushaltsausgleich beraten. \u201eVor uns allen liegt ein Kraftakt\u201c, machte Kommunalminister Ralf J\u00e4ger in Herne deutlich. \u201eDie Konsolidierung der kommunalen Finanzen ist aber zwingend notwendig. Der Sparkurs ist dann ertr\u00e4glich, wenn am Ende ein realistisches Ziel steht. Unser gemeinsames Ziel ist, die kommunale Demokratie zu st\u00e4rken und die R\u00e4te wieder in die Lage versetzen, eigenverantwortlich f\u00fcr die B\u00fcrgerinnen und B\u00fcrger zu handeln\u201c, betonte J\u00e4ger.\n<p class=\"syndicated-attribution\"><br \/><a target='_blank' href='http:\/\/www.nrw.de\/landesregierung\/task-force-beraet-staerkungspakt-kommunen-12353\/'> komplette Meldung auf Meldungen aus dem Ministerium f\u00fcr Inneres und Kommunales lesen<\/a><br \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Eine Task Force wird ab sofort die 34-St\u00e4rkungspakt-Kommunen auf ihrem Weg zum Haushaltsausgleich beraten. \u201eVor uns allen liegt ein Kraftakt\u201c, machte Kommunalminister Ralf J\u00e4ger in Herne deutlich. \u201eDie Konsolidierung der kommunalen Finanzen ist&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-8368","post","type-post","status-publish","format-standard","hentry","category-nordrhein-westfalen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Task Force ber\u00e4t St\u00e4rkungspakt-Kommunen \/ Politische Repr\u00e4sentanten \u00fcbernehmen Vermittlerrolle<\/title>\n<meta name=\"description\" content=\"Eine Task Force wird ab sofort die 34-St\u00e4rkungspakt-Kommunen auf ihrem Weg zum Haushaltsausgleich beraten. \u201eVor uns allen liegt ein Kraftakt\u201c, machte Kommunalminister Ralf J\u00e4ger in Herne deutlich. \u201eDie Konsolidierung der kommunalen Finanzen ist...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.prosos.org\/sosvz\/task-force-berat-starkungspakt-kommunen-politische-reprasentanten-ubernehmen-vermittlerrolle-8368.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Task Force ber\u00e4t St\u00e4rkungspakt-Kommunen \/ Politische Repr\u00e4sentanten \u00fcbernehmen Vermittlerrolle\" \/>\n<meta property=\"og:description\" content=\"Eine Task Force wird ab sofort die 34-St\u00e4rkungspakt-Kommunen auf ihrem Weg zum Haushaltsausgleich beraten. \u201eVor uns allen liegt ein Kraftakt\u201c, machte Kommunalminister Ralf J\u00e4ger in Herne deutlich. \u201eDie Konsolidierung der kommunalen Finanzen ist...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.prosos.org\/sosvz\/task-force-berat-starkungspakt-kommunen-politische-reprasentanten-ubernehmen-vermittlerrolle-8368.html\" \/>\n<meta property=\"og:site_name\" content=\"ProSOS - sosVZ\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-19T10:13:28+00:00\" \/>\n<meta name=\"author\" content=\"Meldungen aus dem Ministerium f\u00fcr Inneres und Kommunales\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meldungen aus dem Ministerium f\u00fcr Inneres und Kommunales\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/task-force-berat-starkungspakt-kommunen-politische-reprasentanten-ubernehmen-vermittlerrolle-8368.html\",\"url\":\"https:\/\/www.prosos.org\/sosvz\/task-force-berat-starkungspakt-kommunen-politische-reprasentanten-ubernehmen-vermittlerrolle-8368.html\",\"name\":\"Task Force ber\u00e4t St\u00e4rkungspakt-Kommunen \/ Politische Repr\u00e4sentanten \u00fcbernehmen Vermittlerrolle\",\"isPartOf\":{\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#website\"},\"datePublished\":\"2012-01-19T10:13:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/735424b2638dcb5efa8c9ab9a6c22728\"},\"description\":\"Eine Task Force wird ab sofort die 34-St\u00e4rkungspakt-Kommunen auf ihrem Weg zum Haushaltsausgleich beraten. \u201eVor uns allen liegt ein Kraftakt\u201c, machte Kommunalminister Ralf J\u00e4ger in Herne deutlich. \u201eDie Konsolidierung der kommunalen Finanzen ist...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.prosos.org\/sosvz\/task-force-berat-starkungspakt-kommunen-politische-reprasentanten-ubernehmen-vermittlerrolle-8368.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.prosos.org\/sosvz\/task-force-berat-starkungspakt-kommunen-politische-reprasentanten-ubernehmen-vermittlerrolle-8368.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/task-force-berat-starkungspakt-kommunen-politische-reprasentanten-ubernehmen-vermittlerrolle-8368.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.prosos.org\/sosvz\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Task Force ber\u00e4t St\u00e4rkungspakt-Kommunen \/ Politische Repr\u00e4sentanten \u00fcbernehmen Vermittlerrolle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#website\",\"url\":\"https:\/\/www.prosos.org\/sosvz\/\",\"name\":\"ProSOS - sosVZ\",\"description\":\"Die Coummunity f\u00fcr Polizei, Feuerwehr, Rettungsdienste und Selbstschutz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.prosos.org\/sosvz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/735424b2638dcb5efa8c9ab9a6c22728\",\"name\":\"Meldungen aus dem Ministerium f\u00fcr Inneres und Kommunales\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/231670e3778c4c209869382f3cd17f8d5763ee6585a91307b82209e0dc5cf3e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/231670e3778c4c209869382f3cd17f8d5763ee6585a91307b82209e0dc5cf3e9?s=96&d=mm&r=g\",\"caption\":\"Meldungen aus dem Ministerium f\u00fcr Inneres und Kommunales\"},\"sameAs\":[\"http:\/\/www.nrw.de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Task Force ber\u00e4t St\u00e4rkungspakt-Kommunen \/ Politische Repr\u00e4sentanten \u00fcbernehmen Vermittlerrolle","description":"Eine Task Force wird ab sofort die 34-St\u00e4rkungspakt-Kommunen auf ihrem Weg zum Haushaltsausgleich beraten. \u201eVor uns allen liegt ein Kraftakt\u201c, machte Kommunalminister Ralf J\u00e4ger in Herne deutlich. \u201eDie Konsolidierung der kommunalen Finanzen ist...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.prosos.org\/sosvz\/task-force-berat-starkungspakt-kommunen-politische-reprasentanten-ubernehmen-vermittlerrolle-8368.html","og_locale":"de_DE","og_type":"article","og_title":"Task Force ber\u00e4t St\u00e4rkungspakt-Kommunen \/ Politische Repr\u00e4sentanten \u00fcbernehmen Vermittlerrolle","og_description":"Eine Task Force wird ab sofort die 34-St\u00e4rkungspakt-Kommunen auf ihrem Weg zum Haushaltsausgleich beraten. \u201eVor uns allen liegt ein Kraftakt\u201c, machte Kommunalminister Ralf J\u00e4ger in Herne deutlich. \u201eDie Konsolidierung der kommunalen Finanzen ist...","og_url":"https:\/\/www.prosos.org\/sosvz\/task-force-berat-starkungspakt-kommunen-politische-reprasentanten-ubernehmen-vermittlerrolle-8368.html","og_site_name":"ProSOS - sosVZ","article_published_time":"2012-01-19T10:13:28+00:00","author":"Meldungen aus dem Ministerium f\u00fcr Inneres und Kommunales","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Meldungen aus dem Ministerium f\u00fcr Inneres und Kommunales"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.prosos.org\/sosvz\/task-force-berat-starkungspakt-kommunen-politische-reprasentanten-ubernehmen-vermittlerrolle-8368.html","url":"https:\/\/www.prosos.org\/sosvz\/task-force-berat-starkungspakt-kommunen-politische-reprasentanten-ubernehmen-vermittlerrolle-8368.html","name":"Task Force ber\u00e4t St\u00e4rkungspakt-Kommunen \/ Politische Repr\u00e4sentanten \u00fcbernehmen Vermittlerrolle","isPartOf":{"@id":"https:\/\/www.prosos.org\/sosvz\/#website"},"datePublished":"2012-01-19T10:13:28+00:00","author":{"@id":"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/735424b2638dcb5efa8c9ab9a6c22728"},"description":"Eine Task Force wird ab sofort die 34-St\u00e4rkungspakt-Kommunen auf ihrem Weg zum Haushaltsausgleich beraten. \u201eVor uns allen liegt ein Kraftakt\u201c, machte Kommunalminister Ralf J\u00e4ger in Herne deutlich. \u201eDie Konsolidierung der kommunalen Finanzen ist...","breadcrumb":{"@id":"https:\/\/www.prosos.org\/sosvz\/task-force-berat-starkungspakt-kommunen-politische-reprasentanten-ubernehmen-vermittlerrolle-8368.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.prosos.org\/sosvz\/task-force-berat-starkungspakt-kommunen-politische-reprasentanten-ubernehmen-vermittlerrolle-8368.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.prosos.org\/sosvz\/task-force-berat-starkungspakt-kommunen-politische-reprasentanten-ubernehmen-vermittlerrolle-8368.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.prosos.org\/sosvz"},{"@type":"ListItem","position":2,"name":"Task Force ber\u00e4t St\u00e4rkungspakt-Kommunen \/ Politische Repr\u00e4sentanten \u00fcbernehmen Vermittlerrolle"}]},{"@type":"WebSite","@id":"https:\/\/www.prosos.org\/sosvz\/#website","url":"https:\/\/www.prosos.org\/sosvz\/","name":"ProSOS - sosVZ","description":"Die Coummunity f\u00fcr Polizei, Feuerwehr, Rettungsdienste und Selbstschutz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.prosos.org\/sosvz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/735424b2638dcb5efa8c9ab9a6c22728","name":"Meldungen aus dem Ministerium f\u00fcr Inneres und Kommunales","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.prosos.org\/sosvz\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/231670e3778c4c209869382f3cd17f8d5763ee6585a91307b82209e0dc5cf3e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/231670e3778c4c209869382f3cd17f8d5763ee6585a91307b82209e0dc5cf3e9?s=96&d=mm&r=g","caption":"Meldungen aus dem Ministerium f\u00fcr Inneres und Kommunales"},"sameAs":["http:\/\/www.nrw.de"]}]}},"_links":{"self":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/posts\/8368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/comments?post=8368"}],"version-history":[{"count":0,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/posts\/8368\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/media?parent=8368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/categories?post=8368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.prosos.org\/sosvz\/wp-json\/wp\/v2\/tags?post=8368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}